{"id":2749,"date":"2026-06-23T09:59:11","date_gmt":"2026-06-23T07:59:11","guid":{"rendered":"https:\/\/www.alientech-tools.com\/it\/dealers\/alientech-uk-official-branch-towcester\/"},"modified":"2026-07-22T17:08:16","modified_gmt":"2026-07-22T15:08:16","slug":"alientech-uk-official-branch-towcester","status":"publish","type":"att_dealer","link":"https:\/\/www.alientech-tools.com\/it\/dealers\/alientech-uk-official-branch-towcester\/","title":{"rendered":"Alientech UK"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","att_product":[],"att_dealer_country":[107],"att_dealer_region":[128],"att_dealer_type":[29],"att_dealer_capability":[802,803,793,794,804,34,35],"class_list":["post-2749","att_dealer","type-att_dealer","status-publish","hentry","att_dealer_country-united-kingdom","att_dealer_region-united-kingdom-northampton","att_dealer_type-filiale","att_dealer_capability-dynodrive","att_dealer_capability-ecm-titanium","att_dealer_capability-kess3-master","att_dealer_capability-kess3-slave","att_dealer_capability-powergate","att_dealer_capability-sales","att_dealer_capability-support"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alientech UK - Alientech<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alientech-tools.com\/it\/dealers\/alientech-uk-official-branch-towcester\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alientech UK - Alientech\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alientech-tools.com\/it\/dealers\/alientech-uk-official-branch-towcester\/\" \/>\n<meta property=\"og:site_name\" content=\"Alientech\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AlientechItalia\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-22T15:08:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/dealers\\\/alientech-uk-official-branch-towcester\\\/\",\"url\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/dealers\\\/alientech-uk-official-branch-towcester\\\/\",\"name\":\"Alientech UK - Alientech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/#website\"},\"datePublished\":\"2026-06-23T07:59:11+00:00\",\"dateModified\":\"2026-07-22T15:08:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/dealers\\\/alientech-uk-official-branch-towcester\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/dealers\\\/alientech-uk-official-branch-towcester\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/dealers\\\/alientech-uk-official-branch-towcester\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rivenditori\",\"item\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/dealers\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alientech UK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/\",\"name\":\"Alientech\",\"description\":\"Tools for ECU remapping\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/#organization\",\"name\":\"Alientech S.r.l.\",\"url\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alientech-tools.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/alientech_logo.webp\",\"contentUrl\":\"https:\\\/\\\/www.alientech-tools.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/alientech_logo.webp\",\"width\":484,\"height\":252,\"caption\":\"Alientech S.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AlientechItalia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/alientech_official\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCIxpLqJkBSnlqtxJhch5PqQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alientech UK - Alientech","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alientech-tools.com\/it\/dealers\/alientech-uk-official-branch-towcester\/","og_locale":"it_IT","og_type":"article","og_title":"Alientech UK - Alientech","og_url":"https:\/\/www.alientech-tools.com\/it\/dealers\/alientech-uk-official-branch-towcester\/","og_site_name":"Alientech","article_publisher":"https:\/\/www.facebook.com\/AlientechItalia\/","article_modified_time":"2026-07-22T15:08:16+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alientech-tools.com\/it\/dealers\/alientech-uk-official-branch-towcester\/","url":"https:\/\/www.alientech-tools.com\/it\/dealers\/alientech-uk-official-branch-towcester\/","name":"Alientech UK - Alientech","isPartOf":{"@id":"https:\/\/www.alientech-tools.com\/it\/#website"},"datePublished":"2026-06-23T07:59:11+00:00","dateModified":"2026-07-22T15:08:16+00:00","breadcrumb":{"@id":"https:\/\/www.alientech-tools.com\/it\/dealers\/alientech-uk-official-branch-towcester\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alientech-tools.com\/it\/dealers\/alientech-uk-official-branch-towcester\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.alientech-tools.com\/it\/dealers\/alientech-uk-official-branch-towcester\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alientech-tools.com\/it\/"},{"@type":"ListItem","position":2,"name":"Rivenditori","item":"https:\/\/www.alientech-tools.com\/it\/dealers\/"},{"@type":"ListItem","position":3,"name":"Alientech UK"}]},{"@type":"WebSite","@id":"https:\/\/www.alientech-tools.com\/it\/#website","url":"https:\/\/www.alientech-tools.com\/it\/","name":"Alientech","description":"Tools for ECU remapping","publisher":{"@id":"https:\/\/www.alientech-tools.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alientech-tools.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.alientech-tools.com\/it\/#organization","name":"Alientech S.r.l.","url":"https:\/\/www.alientech-tools.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.alientech-tools.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/04\/alientech_logo.webp","contentUrl":"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/04\/alientech_logo.webp","width":484,"height":252,"caption":"Alientech S.r.l."},"image":{"@id":"https:\/\/www.alientech-tools.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AlientechItalia\/","https:\/\/www.instagram.com\/alientech_official\/","https:\/\/www.youtube.com\/channel\/UCIxpLqJkBSnlqtxJhch5PqQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/att_dealer\/2749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/att_dealer"}],"about":[{"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/types\/att_dealer"}],"version-history":[{"count":2,"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/att_dealer\/2749\/revisions"}],"predecessor-version":[{"id":358875,"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/att_dealer\/2749\/revisions\/358875"}],"wp:attachment":[{"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/media?parent=2749"}],"wp:term":[{"taxonomy":"att_product","embeddable":true,"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/att_product?post=2749"},{"taxonomy":"att_dealer_country","embeddable":true,"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/att_dealer_country?post=2749"},{"taxonomy":"att_dealer_region","embeddable":true,"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/att_dealer_region?post=2749"},{"taxonomy":"att_dealer_type","embeddable":true,"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/att_dealer_type?post=2749"},{"taxonomy":"att_dealer_capability","embeddable":true,"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/att_dealer_capability?post=2749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}