{"id":3723,"date":"2026-06-23T13:44:29","date_gmt":"2026-06-23T11:44:29","guid":{"rendered":"https:\/\/www.alientech-tools.com\/?post_type=att_accessory&#038;p=3723"},"modified":"2026-08-12T11:17:30","modified_gmt":"2026-08-12T09:17:30","slug":"kess3-cavo-cnh-valtra-rotondo-a-8-pin","status":"publish","type":"att_accessory","link":"https:\/\/www.alientech-tools.com\/it\/accessories\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\/","title":{"rendered":"Cavo CNH &#8211; Valtra rotondo a 8 pin"},"content":{"rendered":"<p>Cavo di collegamento dedicato per veicoli Valtra dotati di presa diagnostica rotonda a 8 pin. Consente l\u2019interfacciamento con il veicolo in modalit\u00e0 OBD tramite la relativa presa di diagnosi, permettendo l\u2019esecuzione delle operazioni di programmazione previste dallo strumento KESS3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cavo di collegamento dedicato per veicoli Valtra dotati di presa diagnostica rotonda a 8 pin. Consente l\u2019interfacciamento con il veicolo in modalit\u00e0 OBD tramite la relativa presa di diagnosi, permettendo l\u2019esecuzione delle operazioni di programmazione previste dallo strumento KESS3.<\/p>\n","protected":false},"featured_media":368155,"template":"","meta":{"_acf_changed":false,"attsct_internal_code":"144300K228","attsct_compatibility_note":"","attsct_download_asset_ids":[],"attsct_featured":false,"attsct_gallery_ids":[368156,368157],"_members_access_role":[],"_members_access_error":""},"att-accessory-types":[],"att-market-segments":[],"att_product":[24],"class_list":["post-3723","att_accessory","type-att_accessory","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cavo CNH - Valtra rotondo a 8 pin - Alientech<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alientech-tools.com\/it\/accessories\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cavo CNH - Valtra rotondo a 8 pin - Alientech\" \/>\n<meta property=\"og:description\" content=\"Cavo di collegamento dedicato per veicoli Valtra dotati di presa diagnostica rotonda a 8 pin. Consente l\u2019interfacciamento con il veicolo in modalit\u00e0 OBD tramite la relativa presa di diagnosi, permettendo l\u2019esecuzione delle operazioni di programmazione previste dallo strumento KESS3.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alientech-tools.com\/it\/accessories\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\/\" \/>\n<meta property=\"og:site_name\" content=\"Alientech\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AlientechItalia\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T09:17:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/06\/IMG_8681.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"5712\" \/>\n\t<meta property=\"og:image:height\" content=\"4284\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/accessories\\\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\\\/\",\"url\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/accessories\\\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\\\/\",\"name\":\"Cavo CNH - Valtra rotondo a 8 pin - Alientech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/accessories\\\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/accessories\\\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alientech-tools.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/IMG_8681.webp\",\"datePublished\":\"2026-06-23T11:44:29+00:00\",\"dateModified\":\"2026-08-12T09:17:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/accessories\\\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/accessories\\\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/accessories\\\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alientech-tools.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/IMG_8681.webp\",\"contentUrl\":\"https:\\\/\\\/www.alientech-tools.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/IMG_8681.webp\",\"width\":5712,\"height\":4284},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/accessories\\\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accessori\",\"item\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/accessories\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cavo CNH &#8211; Valtra rotondo a 8 pin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/\",\"name\":\"Alientech\",\"description\":\"Tools for ECU remapping\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/#organization\",\"name\":\"Alientech S.r.l.\",\"url\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alientech-tools.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/alientech_logo.webp\",\"contentUrl\":\"https:\\\/\\\/www.alientech-tools.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/alientech_logo.webp\",\"width\":484,\"height\":252,\"caption\":\"Alientech S.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AlientechItalia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/alientech_official\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCIxpLqJkBSnlqtxJhch5PqQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cavo CNH - Valtra rotondo a 8 pin - Alientech","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alientech-tools.com\/it\/accessories\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\/","og_locale":"it_IT","og_type":"article","og_title":"Cavo CNH - Valtra rotondo a 8 pin - Alientech","og_description":"Cavo di collegamento dedicato per veicoli Valtra dotati di presa diagnostica rotonda a 8 pin. Consente l\u2019interfacciamento con il veicolo in modalit\u00e0 OBD tramite la relativa presa di diagnosi, permettendo l\u2019esecuzione delle operazioni di programmazione previste dallo strumento KESS3.","og_url":"https:\/\/www.alientech-tools.com\/it\/accessories\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\/","og_site_name":"Alientech","article_publisher":"https:\/\/www.facebook.com\/AlientechItalia\/","article_modified_time":"2026-08-12T09:17:30+00:00","og_image":[{"width":5712,"height":4284,"url":"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/06\/IMG_8681.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alientech-tools.com\/it\/accessories\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\/","url":"https:\/\/www.alientech-tools.com\/it\/accessories\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\/","name":"Cavo CNH - Valtra rotondo a 8 pin - Alientech","isPartOf":{"@id":"https:\/\/www.alientech-tools.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alientech-tools.com\/it\/accessories\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\/#primaryimage"},"image":{"@id":"https:\/\/www.alientech-tools.com\/it\/accessories\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/06\/IMG_8681.webp","datePublished":"2026-06-23T11:44:29+00:00","dateModified":"2026-08-12T09:17:30+00:00","breadcrumb":{"@id":"https:\/\/www.alientech-tools.com\/it\/accessories\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alientech-tools.com\/it\/accessories\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.alientech-tools.com\/it\/accessories\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\/#primaryimage","url":"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/06\/IMG_8681.webp","contentUrl":"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/06\/IMG_8681.webp","width":5712,"height":4284},{"@type":"BreadcrumbList","@id":"https:\/\/www.alientech-tools.com\/it\/accessories\/kess3-cavo-cnh-valtra-rotondo-a-8-pin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alientech-tools.com\/it\/"},{"@type":"ListItem","position":2,"name":"Accessori","item":"https:\/\/www.alientech-tools.com\/it\/accessories\/"},{"@type":"ListItem","position":3,"name":"Cavo CNH &#8211; Valtra rotondo a 8 pin"}]},{"@type":"WebSite","@id":"https:\/\/www.alientech-tools.com\/it\/#website","url":"https:\/\/www.alientech-tools.com\/it\/","name":"Alientech","description":"Tools for ECU remapping","publisher":{"@id":"https:\/\/www.alientech-tools.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alientech-tools.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.alientech-tools.com\/it\/#organization","name":"Alientech S.r.l.","url":"https:\/\/www.alientech-tools.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.alientech-tools.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/04\/alientech_logo.webp","contentUrl":"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/04\/alientech_logo.webp","width":484,"height":252,"caption":"Alientech S.r.l."},"image":{"@id":"https:\/\/www.alientech-tools.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AlientechItalia\/","https:\/\/www.instagram.com\/alientech_official\/","https:\/\/www.youtube.com\/channel\/UCIxpLqJkBSnlqtxJhch5PqQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/att-accessories\/3723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/att-accessories"}],"about":[{"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/types\/att_accessory"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/media\/368155"}],"wp:attachment":[{"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/media?parent=3723"}],"wp:term":[{"taxonomy":"att_accessory_type","embeddable":true,"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/att-accessory-types?post=3723"},{"taxonomy":"att_market_segment","embeddable":true,"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/att-market-segments?post=3723"},{"taxonomy":"att_product","embeddable":true,"href":"https:\/\/www.alientech-tools.com\/it\/wp-json\/wp\/v2\/att_product?post=3723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}