{"id":3690,"date":"2026-06-23T13:44:33","date_gmt":"2026-06-23T11:44:33","guid":{"rendered":"https:\/\/www.alientech-tools.com\/?post_type=att_accessory&#038;p=3690"},"modified":"2026-08-14T11:34:45","modified_gmt":"2026-08-14T09:34:45","slug":"kess3-cable-iveco-rond-a-30-broches","status":"publish","type":"att_accessory","link":"https:\/\/www.alientech-tools.com\/fr\/accessories\/kess3-cable-iveco-rond-a-30-broches\/","title":{"rendered":"C\u00e2ble Iveco rond \u00e0 30 broches"},"content":{"rendered":"<p>C\u00e2ble de connexion d\u00e9di\u00e9 pour v\u00e9hicules Iveco \u00e9quip\u00e9s d\u2019un connecteur de diagnostic rond \u00e0 30 broches. Il permet l\u2019interfa\u00e7age avec le v\u00e9hicule en mode OBD via la prise de diagnostic correspondante et l\u2019ex\u00e9cution des op\u00e9rations de programmation support\u00e9es par l\u2019outil KESS3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00e2ble de connexion d\u00e9di\u00e9 pour v\u00e9hicules Iveco \u00e9quip\u00e9s d\u2019un connecteur de diagnostic rond \u00e0 30 broches. Il permet l\u2019interfa\u00e7age avec le v\u00e9hicule en mode OBD via la prise de diagnostic correspondante et l\u2019ex\u00e9cution des op\u00e9rations de programmation support\u00e9es par l\u2019outil KESS3.<\/p>\n","protected":false},"featured_media":368132,"template":"","meta":{"_acf_changed":false,"attsct_internal_code":"144300K209","attsct_compatibility_note":"","attsct_download_asset_ids":[],"attsct_featured":false,"attsct_gallery_ids":[368133,368134],"_members_access_role":[],"_members_access_error":""},"att-accessory-types":[],"att-market-segments":[],"att_product":[24],"class_list":["post-3690","att_accessory","type-att_accessory","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00e2ble Iveco rond \u00e0 30 broches - Alientech<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alientech-tools.com\/fr\/accessories\/kess3-cable-iveco-rond-a-30-broches\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e2ble Iveco rond \u00e0 30 broches - Alientech\" \/>\n<meta property=\"og:description\" content=\"C\u00e2ble de connexion d\u00e9di\u00e9 pour v\u00e9hicules Iveco \u00e9quip\u00e9s d\u2019un connecteur de diagnostic rond \u00e0 30 broches. Il permet l\u2019interfa\u00e7age avec le v\u00e9hicule en mode OBD via la prise de diagnostic correspondante et l\u2019ex\u00e9cution des op\u00e9rations de programmation support\u00e9es par l\u2019outil KESS3.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alientech-tools.com\/fr\/accessories\/kess3-cable-iveco-rond-a-30-broches\/\" \/>\n<meta property=\"og:site_name\" content=\"Alientech\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AlientechItalia\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-14T09:34:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/06\/IMG_8820.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"5712\" \/>\n\t<meta property=\"og:image:height\" content=\"4284\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/accessories\\\/kess3-cable-iveco-rond-a-30-broches\\\/\",\"url\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/accessories\\\/kess3-cable-iveco-rond-a-30-broches\\\/\",\"name\":\"C\u00e2ble Iveco rond \u00e0 30 broches - Alientech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/accessories\\\/kess3-cable-iveco-rond-a-30-broches\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/accessories\\\/kess3-cable-iveco-rond-a-30-broches\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alientech-tools.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/IMG_8820.webp\",\"datePublished\":\"2026-06-23T11:44:33+00:00\",\"dateModified\":\"2026-08-14T09:34:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/accessories\\\/kess3-cable-iveco-rond-a-30-broches\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/accessories\\\/kess3-cable-iveco-rond-a-30-broches\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/accessories\\\/kess3-cable-iveco-rond-a-30-broches\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alientech-tools.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/IMG_8820.webp\",\"contentUrl\":\"https:\\\/\\\/www.alientech-tools.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/IMG_8820.webp\",\"width\":5712,\"height\":4284},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/accessories\\\/kess3-cable-iveco-rond-a-30-broches\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accessories\",\"item\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/accessories\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00e2ble Iveco rond \u00e0 30 broches\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/\",\"name\":\"Alientech\",\"description\":\"Tools for ECU remapping\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/#organization\",\"name\":\"Alientech S.r.l.\",\"url\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alientech-tools.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/alientech_logo.webp\",\"contentUrl\":\"https:\\\/\\\/www.alientech-tools.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/alientech_logo.webp\",\"width\":484,\"height\":252,\"caption\":\"Alientech S.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alientech-tools.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AlientechItalia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/alientech_official\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCIxpLqJkBSnlqtxJhch5PqQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00e2ble Iveco rond \u00e0 30 broches - Alientech","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alientech-tools.com\/fr\/accessories\/kess3-cable-iveco-rond-a-30-broches\/","og_locale":"fr_FR","og_type":"article","og_title":"C\u00e2ble Iveco rond \u00e0 30 broches - Alientech","og_description":"C\u00e2ble de connexion d\u00e9di\u00e9 pour v\u00e9hicules Iveco \u00e9quip\u00e9s d\u2019un connecteur de diagnostic rond \u00e0 30 broches. Il permet l\u2019interfa\u00e7age avec le v\u00e9hicule en mode OBD via la prise de diagnostic correspondante et l\u2019ex\u00e9cution des op\u00e9rations de programmation support\u00e9es par l\u2019outil KESS3.","og_url":"https:\/\/www.alientech-tools.com\/fr\/accessories\/kess3-cable-iveco-rond-a-30-broches\/","og_site_name":"Alientech","article_publisher":"https:\/\/www.facebook.com\/AlientechItalia\/","article_modified_time":"2026-08-14T09:34:45+00:00","og_image":[{"width":5712,"height":4284,"url":"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/06\/IMG_8820.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alientech-tools.com\/fr\/accessories\/kess3-cable-iveco-rond-a-30-broches\/","url":"https:\/\/www.alientech-tools.com\/fr\/accessories\/kess3-cable-iveco-rond-a-30-broches\/","name":"C\u00e2ble Iveco rond \u00e0 30 broches - Alientech","isPartOf":{"@id":"https:\/\/www.alientech-tools.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alientech-tools.com\/fr\/accessories\/kess3-cable-iveco-rond-a-30-broches\/#primaryimage"},"image":{"@id":"https:\/\/www.alientech-tools.com\/fr\/accessories\/kess3-cable-iveco-rond-a-30-broches\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/06\/IMG_8820.webp","datePublished":"2026-06-23T11:44:33+00:00","dateModified":"2026-08-14T09:34:45+00:00","breadcrumb":{"@id":"https:\/\/www.alientech-tools.com\/fr\/accessories\/kess3-cable-iveco-rond-a-30-broches\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alientech-tools.com\/fr\/accessories\/kess3-cable-iveco-rond-a-30-broches\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.alientech-tools.com\/fr\/accessories\/kess3-cable-iveco-rond-a-30-broches\/#primaryimage","url":"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/06\/IMG_8820.webp","contentUrl":"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/06\/IMG_8820.webp","width":5712,"height":4284},{"@type":"BreadcrumbList","@id":"https:\/\/www.alientech-tools.com\/fr\/accessories\/kess3-cable-iveco-rond-a-30-broches\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alientech-tools.com\/fr\/homepage\/"},{"@type":"ListItem","position":2,"name":"Accessories","item":"https:\/\/www.alientech-tools.com\/fr\/accessories\/"},{"@type":"ListItem","position":3,"name":"C\u00e2ble Iveco rond \u00e0 30 broches"}]},{"@type":"WebSite","@id":"https:\/\/www.alientech-tools.com\/fr\/#website","url":"https:\/\/www.alientech-tools.com\/fr\/","name":"Alientech","description":"Tools for ECU remapping","publisher":{"@id":"https:\/\/www.alientech-tools.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alientech-tools.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.alientech-tools.com\/fr\/#organization","name":"Alientech S.r.l.","url":"https:\/\/www.alientech-tools.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.alientech-tools.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/04\/alientech_logo.webp","contentUrl":"https:\/\/www.alientech-tools.com\/wp-content\/uploads\/2026\/04\/alientech_logo.webp","width":484,"height":252,"caption":"Alientech S.r.l."},"image":{"@id":"https:\/\/www.alientech-tools.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AlientechItalia\/","https:\/\/www.instagram.com\/alientech_official\/","https:\/\/www.youtube.com\/channel\/UCIxpLqJkBSnlqtxJhch5PqQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.alientech-tools.com\/fr\/wp-json\/wp\/v2\/att-accessories\/3690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alientech-tools.com\/fr\/wp-json\/wp\/v2\/att-accessories"}],"about":[{"href":"https:\/\/www.alientech-tools.com\/fr\/wp-json\/wp\/v2\/types\/att_accessory"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alientech-tools.com\/fr\/wp-json\/wp\/v2\/media\/368132"}],"wp:attachment":[{"href":"https:\/\/www.alientech-tools.com\/fr\/wp-json\/wp\/v2\/media?parent=3690"}],"wp:term":[{"taxonomy":"att_accessory_type","embeddable":true,"href":"https:\/\/www.alientech-tools.com\/fr\/wp-json\/wp\/v2\/att-accessory-types?post=3690"},{"taxonomy":"att_market_segment","embeddable":true,"href":"https:\/\/www.alientech-tools.com\/fr\/wp-json\/wp\/v2\/att-market-segments?post=3690"},{"taxonomy":"att_product","embeddable":true,"href":"https:\/\/www.alientech-tools.com\/fr\/wp-json\/wp\/v2\/att_product?post=3690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}